{"id":9001,"date":"2025-02-07T22:57:59","date_gmt":"2025-02-07T22:57:59","guid":{"rendered":"https:\/\/npmin.org\/?p=9001"},"modified":"2025-02-07T22:58:00","modified_gmt":"2025-02-07T22:58:00","slug":"owning-relationships","status":"publish","type":"post","link":"https:\/\/npmin.org\/pt\/articles\/owning-relationships\/","title":{"rendered":"Possuindo relacionamentos?"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Quer tenhamos pensado nisso conscientemente ou n\u00e3o, cada um de n\u00f3s assume a responsabilidade pelos relacionamentos em nossas vidas. Isso pode parecer bom, mas ser\u00e1 mesmo?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Quando assumimos a responsabilidade por um relacionamento, assumimos a responsabilidade por seu resultado. Se ele fracassa, percebemos que fracassamos. Se ele d\u00e1 certo, percebemos que tivemos sucesso. Nosso sucesso ou fracasso pessoal est\u00e1, em nossa opini\u00e3o, vinculado ao sucesso ou fracasso de nossos relacionamentos. Por isso, precisamos, de alguma forma, garantir que nossos relacionamentos sejam bem-sucedidos para que possamos ter sucesso.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como um relacionamento envolve duas pessoas, quando assumimos a responsabilidade por um relacionamento, devemos assumir a responsabilidade pela outra pessoa envolvida no relacionamento tamb\u00e9m. Assumimos a responsabilidade por seus pensamentos, palavras, a\u00e7\u00f5es e rea\u00e7\u00f5es, pois estes impactam o resultado do relacionamento. E os responsabilizamos por sua participa\u00e7\u00e3o, ou falta dela, no relacionamento.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se eles se comportam bem e nos toleram bem, estamos em paz no relacionamento, sabendo que ele \u00e9 bem-sucedido. Podemos deix\u00e1-los em paz e deix\u00e1-los se autogovernar, porque eles obviamente est\u00e3o se autogovernando bem, de acordo com nossos padr\u00f5es pessoais. Mas se eles n\u00e3o se comportam bem ou n\u00e3o nos toleram bem, n\u00e3o podemos estar em paz. N\u00e3o podemos deix\u00e1-los em paz e deix\u00e1-los se autogovernar livremente, porque eles obviamente n\u00e3o est\u00e3o se autogovernando bem. Precisamos intervir de alguma forma.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para consertar o relacionamento, precisamos de alguma forma controlar a outra pessoa. Tentamos fazer isso mudando nosso comportamento perto dela. Tentamos convenc\u00ea-la a mudar agindo de forma mais gentil, mais doce, mais complacente ou, de alguma forma, modelando como queremos que ela se comporte conosco. Tentamos mud\u00e1-la por meio de conversas, reclama\u00e7\u00f5es, discuss\u00f5es, etc. Tentamos mud\u00e1-la negando-lhe o bem, ignorando-a, recusando-nos a falar com ela e usando outros m\u00e9todos passivo-agressivos. Tentamos mud\u00e1-la por meio de amea\u00e7as, abusos ou outras manifesta\u00e7\u00f5es de for\u00e7a. E assim por diante.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Na realidade, nunca podemos garantir o sucesso de qualquer relacionamento, porque nunca podemos controlar a outra pessoa. Se medirmos nosso sucesso pessoal pelo &quot;sucesso&quot; do relacionamento como um todo, estaremos sempre sujeitos \u00e0 inseguran\u00e7a e \u00e0 decep\u00e7\u00e3o, sempre tentando controlar e manipular os outros e frequentemente experimentaremos o fracasso em nossos relacionamentos. Tudo isso \u00e9 resultado de acreditar que os relacionamentos me pertencem e que sou respons\u00e1vel pelo sucesso deles.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por que me vejo como dono dos meus relacionamentos? \u00c9 porque nasci com uma condi\u00e7\u00e3o herdada. Essa condi\u00e7\u00e3o se chama natureza pecaminosa. E essa natureza pecaminosa automaticamente me faz pensar algo errado sobre mim mesmo \u2014 que sou um deus, quando na verdade sou uma criatura. Deus \u00e9 o dono de tudo. Tudo veio dEle. Tudo pertence a Ele. N\u00e3o somos donos. Somos mordomos, n\u00e3o das nossas pr\u00f3prias coisas, mas das coisas de Deus. N\u00e3o \u00e9 o seu computador. \u00c9 o computador de Deus. N\u00e3o \u00e9 a sua casa. \u00c9 a casa de Deus. N\u00e3o \u00e9 o seu carro. \u00c9 o carro de Deus. N\u00e3o \u00e9 seu filho. \u00c9 filho de Deus. Seu c\u00f4njuge n\u00e3o lhe pertence. Ele pertence a Deus. N\u00e3o \u00e9 o seu corpo. \u00c9 o corpo de Deus. Ele n\u00e3o s\u00e3o suas qualidades e capacidades. S\u00e3o as qualidades e capacidades de Deus. Tudo pertence a Deus. E voc\u00ea pode ser mordomo de tudo o que Ele lhe d\u00e1 mordomia, enquanto Ele lhe der essa mordomia.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como tudo pertence a Deus, voc\u00ea tamb\u00e9m pertence a Ele. Voc\u00ea \u00e9 respons\u00e1vel perante Deus, e somente a Deus, pois pertence somente a Deus. Voc\u00ea n\u00e3o \u00e9 respons\u00e1vel perante os outros ao seu redor, incluindo seu c\u00f4njuge. Voc\u00ea \u00e9 respons\u00e1vel perante Deus. Mas sua responsabilidade perante Deus n\u00e3o o deixa indiferente aos outros. Voc\u00ea \u00e9 respons\u00e1vel perante Deus pela forma como trata os outros, pois eles tamb\u00e9m pertencem a Ele. E a devida responsabilidade perante Deus significa que voc\u00ea ama os outros, os trata como Cristo os trataria e pensa bem deles, mesmo quando n\u00e3o est\u00e3o cientes disso, porque voc\u00ea sabe que Deus est\u00e1 sempre ciente. Voc\u00ea n\u00e3o \u00e9 gentil apenas quando eles est\u00e3o olhando ou ouvindo. Voc\u00ea \u00e9 gentil o tempo todo porque Deus est\u00e1 sempre olhando e ouvindo.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;Pelo que voc\u00ea \u00e9 respons\u00e1vel perante Deus? Voc\u00ea \u00e9 respons\u00e1vel perante Deus pelo que os outros pensam? O que eles dizem? O que eles fazem? Como eles reagem? Ou pelas escolhas que eles fazem? Claro que n\u00e3o! Voc\u00ea s\u00f3 \u00e9 respons\u00e1vel perante Deus pelo que pensa, diz, faz e como reage. Por qu\u00ea? Porque voc\u00ea s\u00f3 \u00e9 respons\u00e1vel pelas suas pr\u00f3prias escolhas e decis\u00f5es, n\u00e3o pelas escolhas ou decis\u00f5es de outra pessoa.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Deus criou cada pessoa com sua pr\u00f3pria mente, sua pr\u00f3pria vontade, seu pr\u00f3prio autogoverno. E ningu\u00e9m \u00e9 respons\u00e1vel pelo autogoverno de ningu\u00e9m. Nem mesmo Deus se responsabiliza pelo autogoverno de ningu\u00e9m. Sim, somos respons\u00e1veis perante Ele pelo nosso autogoverno porque pertencemos a Ele. Mas Ele n\u00e3o \u00e9 respons\u00e1vel por como nos governamos. Somente n\u00f3s somos.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;Quando assumimos a responsabilidade por um relacionamento, nos tornamos respons\u00e1veis tamb\u00e9m pela outra pessoa no relacionamento. Isso significa que assumimos a responsabilidade por seus pensamentos, cren\u00e7as, escolhas, decis\u00f5es, palavras e a\u00e7\u00f5es \u2014 seu autogoverno. Estamos agora entrando em um territ\u00f3rio em que nem mesmo Deus entraria. Agora, responsabilizo a outra pessoa no relacionamento perante mim, porque me tornei respons\u00e1vel por ela. Suas palavras, a\u00e7\u00f5es e rea\u00e7\u00f5es agora eu assumo como algo pessoal, porque vejo tudo como minha pr\u00f3pria responsabilidade. E se ela n\u00e3o estiver falando, agindo ou reagindo bem, considero isso uma ofensa pessoal contra mim, porque ela \u00e9 respons\u00e1vel perante mim. E como o resultado do relacionamento \u00e9 minha responsabilidade, porque eu sou o dono do relacionamento, devo tentar consert\u00e1-la ou corrigi-la de alguma forma para garantir que o relacionamento continue sendo um sucesso \u2014 para que eu possa continuar sendo um sucesso.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Os resultados de assumir a responsabilidade de um relacionamento s\u00e3o muitos:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Medo do fracasso<\/li>\n\n\n\n<li>Dependendo da outra pessoa<\/li>\n\n\n\n<li>Levando suas palavras e a\u00e7\u00f5es para o lado pessoal<\/li>\n\n\n\n<li>Frustra\u00e7\u00e3o<\/li>\n\n\n\n<li>Desapontamento<\/li>\n\n\n\n<li>Sentindo-se fora de controle<\/li>\n\n\n\n<li>Manipula\u00e7\u00e3o\u00a0<\/li>\n\n\n\n<li>Conflito<\/li>\n\n\n\n<li>Separa\u00e7\u00e3o<\/li>\n\n\n\n<li>Falha do relacionamento<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Qual \u00e9 a solu\u00e7\u00e3o para este problema? \u00c9 ter convic\u00e7\u00e3o da verdade. E qual \u00e9 a verdade? A verdade \u00e9 que voc\u00ea nunca \u00e9 dono de um \u00fanico relacionamento em que esteja. Voc\u00ea \u00e9 apenas um administrador de cada relacionamento. Voc\u00ea nunca \u00e9 respons\u00e1vel pelo que a outra pessoa pensa, diz, faz ou por como ela se autogoverna. Voc\u00ea s\u00f3 \u00e9 respons\u00e1vel pelo que pensa, diz, faz e por como voc\u00ea se autogoverna. E voc\u00ea nunca \u00e9 respons\u00e1vel pelo resultado do relacionamento, porque o resultado do relacionamento depende n\u00e3o apenas de voc\u00ea, mas tamb\u00e9m da outra pessoa. E voc\u00ea nunca pode controlar ou garantir o lado dela no relacionamento.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como administrador de cada relacionamento, voc\u00ea assume a responsabilidade apenas pelo seu lado. Voc\u00ea assume a responsabilidade pelo que pensa, diz, faz, como reage e como participa do relacionamento. Voc\u00ea reconhece que \u00e9 respons\u00e1vel somente perante Deus pelo seu autogoverno no relacionamento, e que se autogoverna em harmonia com a vontade de Deus, independentemente do que a outra pessoa pense a respeito \u2014 pois sua responsabilidade \u00e9 perante Deus, n\u00e3o perante a outra pessoa.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Novamente, isso n\u00e3o o torna insens\u00edvel ou indiferente aos outros. Muito pelo contr\u00e1rio. Quando voc\u00ea tem Deus como sua fonte e sabe que est\u00e1 administrando o relacionamento para Ele, voc\u00ea se apropria do Seu grande e compassivo amor para poder dar esse mesmo amor compassivo \u00e0 outra pessoa no relacionamento. Voc\u00ea a ama. Voc\u00ea se interessa pelo bem-estar dela. Voc\u00ea vive para servir aos seus melhores interesses. Mas voc\u00ea n\u00e3o \u00e9 controlado pelos pensamentos ou opini\u00f5es dela. Voc\u00ea \u00e9 controlado apenas pelos pensamentos de Deus.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Voc\u00ea se consola com o fato de estar servindo como mordomo de Deus, tomando os recursos necess\u00e1rios de Deus com o prop\u00f3sito de d\u00e1-los \u00e0 outra pessoa no relacionamento. Voc\u00ea leva sua mordomia a s\u00e9rio, independentemente do que a outra pessoa no relacionamento esteja fazendo. Se ela est\u00e1 se comportando mal, isso \u00e9 problema pessoal dela. Voc\u00ea sente pena dela por agir assim. Voc\u00ea tem pena dela. Voc\u00ea ora por ela. Voc\u00ea anseia pela liberdade dela. Mas voc\u00ea continua sendo um mordomo fiel de Deus para essa pessoa, independentemente de como ela esteja se comportando. Voc\u00ea n\u00e3o precisa que ela esteja bem para que voc\u00ea esteja bem. Voc\u00ea s\u00f3 precisa que Deus esteja bem para que voc\u00ea esteja bem.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Voc\u00ea mede o sucesso n\u00e3o pelo resultado do relacionamento, mas pela sua pr\u00f3pria administra\u00e7\u00e3o dos recursos de Deus para a outra pessoa. Sucesso \u00e9 ter Deus como sua fonte e receber de Deus tudo o que voc\u00ea precisa para poder dar livremente \u00e0 outra pessoa. Se ela estiver se comportando bem, voc\u00ea recebe de Deus para dar. Se ela n\u00e3o estiver se comportando bem, voc\u00ea recebe de Deus para dar. Se ela estiver feliz, voc\u00ea recebe de Deus para dar. Se ela estiver triste, voc\u00ea recebe de Deus para dar. Voc\u00ea pode ter sucesso independentemente de como ela se comporta, do que ela diz, de como ela responde ou do que ela acredita, porque o seu sucesso n\u00e3o depende dela. Depende apenas de Deus e de voc\u00ea.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ent\u00e3o, se eles decidirem te deixar ou desistir do relacionamento, voc\u00ea n\u00e3o leva isso para o lado pessoal. Voc\u00ea n\u00e3o v\u00ea isso como uma perda pessoal. Voc\u00ea n\u00e3o v\u00ea isso como um fracasso pessoal. Voc\u00ea os ama. Voc\u00ea sofre por eles. Voc\u00ea tem pena deles. Voc\u00ea sabe que eles n\u00e3o s\u00e3o livres, porque n\u00e3o est\u00e3o aceitando o amor de Deus oferecido a eles por seu interm\u00e9dio. Voc\u00ea deseja a liberdade deles e est\u00e1 disposto a fazer qualquer coisa que Deus queira que voc\u00ea fa\u00e7a para ajud\u00e1-los na liberdade deles. Mas voc\u00ea n\u00e3o precisa deles e pode deix\u00e1-los ir se eles escolherem ir. Voc\u00ea s\u00f3 precisa de Deus e n\u00e3o pode deix\u00e1-Lo ir. O amor os deixa livres para se autogovernarem, mesmo quando se autogovernam de forma errada e destrutiva. Isso \u00e9 liberdade. E ela s\u00f3 vem como resultado de ser um mordomo, n\u00e3o um dono.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Claramente, voc\u00ea n\u00e3o passa imediatamente de dono para mordomo. Voc\u00ea n\u00e3o passa imediatamente de sempre levar as coisas para o lado pessoal e tentar controlar o resultado de seus relacionamentos para nunca levar as coisas para o lado pessoal e deixar a outra pessoa no relacionamento livre para se autogovernar. H\u00e1 um per\u00edodo (geralmente um per\u00edodo muito longo) de transi\u00e7\u00e3o. Como \u00e9 esse per\u00edodo de transi\u00e7\u00e3o? Parece muito com ser o dono no come\u00e7o. Parece muito com ser um mordomo no final. E \u00e9 uma experi\u00eancia de idas e vindas no meio. \u00c9 como um beb\u00ea aprendendo a andar. Levantar e cair faz parte do processo de aprender a andar. E o sucesso \u00e9 determinado por se levantar novamente ap\u00f3s cada queda. No come\u00e7o, h\u00e1 muitas quedas. Muito tempo gasto no ch\u00e3o. Muito esfor\u00e7o para se levantar novamente. Mas, com o tempo, voc\u00ea se levanta mais r\u00e1pido, fica em p\u00e9 por mais tempo e trope\u00e7a em cada vez menos coisas.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Inicialmente, voc\u00ea aprende intelectualmente a verdade de que relacionamentos n\u00e3o lhe pertencem e que voc\u00ea n\u00e3o \u00e9 respons\u00e1vel pela forma como a outra pessoa participa do relacionamento. Mas quando ela n\u00e3o se comporta de acordo com seus padr\u00f5es, voc\u00ea leva para o lado pessoal, fica chateado, tenta controlar os resultados, etc. (voc\u00ea cai). O que voc\u00ea faz quando isso acontece? Voc\u00ea se levanta. Voc\u00ea se lembra da verdade. Voc\u00ea pede a Deus para ajudar a trazer essa verdade ao seu cora\u00e7\u00e3o para que a convic\u00e7\u00e3o se instale. Voc\u00ea traz suas respostas erradas \u00e0 cruz e pede a Deus para substituir sua natureza ca\u00edda pela natureza n\u00e3o ca\u00edda Dele na cruz. Voc\u00ea aceita a vida de Cristo em troca da sua vida. E na confian\u00e7a e no poder da natureza de Cristo, voc\u00ea retorna ao relacionamento com a verdade no amor e no poder de Deus. Cada vez que voc\u00ea cair, n\u00e3o se culpe. Apenas volte para a cruz e se levante. Com o tempo, com a repeti\u00e7\u00e3o e no contexto da entrega, o Esp\u00edrito Santo trar\u00e1 essa verdade ao seu cora\u00e7\u00e3o, para que voc\u00ea comece a responder cada vez mais automaticamente, em harmonia com a verdade, at\u00e9 perceber que est\u00e1 vivendo a verdade em seus relacionamentos, sem nem mesmo pensar ou se concentrar nela. Isso se torna uma parte natural de como voc\u00ea vive. Este \u00e9 o processo. Leva tempo. Aceite a gra\u00e7a, a paci\u00eancia e a bondade de Deus para com voc\u00ea enquanto voc\u00ea est\u00e1 nesse processo. E saiba que seu Pai Celestial est\u00e1 sorrindo para voc\u00ea enquanto voc\u00ea aprende a andar.&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Whether we have ever thought of it consciously or not, each of us takes ownership of the relationships in our lives. This may seem like a good thing, but is it? When we take ownership of a relationship, we take responsibility for its outcome. If it fails, we perceive that we failed. If it succeeds, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":9003,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[66],"tags":[148,145,143,142,146,141,147,144],"class_list":["post-9001","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-relationships","tag-accountability","tag-conflict","tag-ownership","tag-owning","tag-peace","tag-relationships","tag-responsibility","tag-stewardship"],"acf":[],"_links":{"self":[{"href":"https:\/\/npmin.org\/pt\/wp-json\/wp\/v2\/posts\/9001","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/npmin.org\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/npmin.org\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/npmin.org\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/npmin.org\/pt\/wp-json\/wp\/v2\/comments?post=9001"}],"version-history":[{"count":1,"href":"https:\/\/npmin.org\/pt\/wp-json\/wp\/v2\/posts\/9001\/revisions"}],"predecessor-version":[{"id":9004,"href":"https:\/\/npmin.org\/pt\/wp-json\/wp\/v2\/posts\/9001\/revisions\/9004"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/npmin.org\/pt\/wp-json\/wp\/v2\/media\/9003"}],"wp:attachment":[{"href":"https:\/\/npmin.org\/pt\/wp-json\/wp\/v2\/media?parent=9001"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/npmin.org\/pt\/wp-json\/wp\/v2\/categories?post=9001"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/npmin.org\/pt\/wp-json\/wp\/v2\/tags?post=9001"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}