{"id":9001,"date":"2025-02-07T22:57:59","date_gmt":"2025-02-07T22:57:59","guid":{"rendered":"https:\/\/npmin.org\/?p=9001"},"modified":"2025-02-07T22:58:00","modified_gmt":"2025-02-07T22:58:00","slug":"owning-relationships","status":"publish","type":"post","link":"https:\/\/npmin.org\/fr\/articles\/owning-relationships\/","title":{"rendered":"\u00catre propri\u00e9taire de relations ?"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Que nous y ayons d\u00e9j\u00e0 pens\u00e9 consciemment ou non, chacun de nous prend en charge ses relations. Cela peut para\u00eetre positif, mais est-ce vraiment le cas\u00a0?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lorsque nous prenons en main une relation, nous en assumons la responsabilit\u00e9. Si elle \u00e9choue, nous percevons un \u00e9chec. Si elle r\u00e9ussit, nous percevons une r\u00e9ussite. Notre r\u00e9ussite ou notre \u00e9chec personnel est, selon nous, li\u00e9 \u00e0 la r\u00e9ussite ou \u00e0 l&#039;\u00e9chec de nos relations. C&#039;est pourquoi nous devons, d&#039;une mani\u00e8re ou d&#039;une autre, veiller \u00e0 ce que nos relations soient fructueuses pour r\u00e9ussir.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Puisqu&#039;une relation implique deux personnes, lorsque nous prenons en charge cette relation, nous devons \u00e9galement prendre en charge l&#039;autre personne. Nous assumons la responsabilit\u00e9 de ses pens\u00e9es, de ses paroles, de ses actes et de ses r\u00e9actions, car ceux-ci influencent l&#039;issue de la relation. Et nous la tenons responsable de sa participation, ou de son absence, \u00e0 la relation.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">S&#039;ils se comportent bien et nous tol\u00e8rent bien, nous sommes en paix dans notre relation, sachant qu&#039;elle est fructueuse. Nous pouvons les laisser tranquilles et s&#039;autog\u00e9rer, car ils le font manifestement bien selon nos crit\u00e8res personnels. Mais s&#039;ils ne se comportent pas bien ou ne nous tol\u00e8rent pas bien, nous ne pouvons pas \u00eatre en paix. Nous ne pouvons pas les laisser tranquilles et s&#039;autog\u00e9rer librement, car ils ne le font manifestement pas bien. Nous devons intervenir d&#039;une mani\u00e8re ou d&#039;une autre.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pour am\u00e9liorer la relation, nous devons d&#039;une mani\u00e8re ou d&#039;une autre contr\u00f4ler l&#039;autre personne. Nous tentons d&#039;y parvenir en modifiant notre comportement avec elle. Nous essayons de la convaincre de changer en \u00e9tant nous-m\u00eames plus gentils, plus doux, plus conciliants, ou en donnant l&#039;exemple de la fa\u00e7on dont nous souhaitons qu&#039;elle se comporte envers nous. Nous essayons de la changer par le dialogue, les plaintes, les disputes, etc. Nous essayons de la changer en la privant de bonnes choses, en l&#039;ignorant, en refusant de lui parler et en utilisant d&#039;autres m\u00e9thodes passives-agressives. Nous essayons de la changer par des menaces, des abus ou d&#039;autres formes de violence. Et ainsi de suite.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En r\u00e9alit\u00e9, nous ne pouvons jamais garantir le succ\u00e8s d&#039;une relation, car nous ne pouvons jamais contr\u00f4ler l&#039;autre. Si nous mesurons notre r\u00e9ussite personnelle \u00e0 l&#039;aune de la \u00ab r\u00e9ussite \u00bb de la relation dans son ensemble, nous serons toujours sujets \u00e0 l&#039;ins\u00e9curit\u00e9 et \u00e0 la d\u00e9ception, nous chercherons constamment \u00e0 contr\u00f4ler et \u00e0 manipuler les autres, et nous conna\u00eetrons fr\u00e9quemment des \u00e9checs relationnels. Tout cela r\u00e9sulte de la conviction que les relations nous appartiennent et que nous sommes responsables de leur r\u00e9ussite.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pourquoi me consid\u00e8re-je comme ma\u00eetre de mes relations ? C&#039;est parce que je suis n\u00e9 avec une condition h\u00e9r\u00e9ditaire. Cette condition s&#039;appelle la nature p\u00e9cheresse. Et cette nature p\u00e9cheresse me conduit automatiquement \u00e0 penser quelque chose de faux \u00e0 mon sujet : je me prends pour un dieu alors que je suis une cr\u00e9ature. Dieu est le propri\u00e9taire de tout. Tout vient de Lui. Tout Lui appartient. Nous ne sommes pas propri\u00e9taires. Nous sommes les intendants, non pas de nos biens, mais des biens de Dieu. Ce n&#039;est pas votre ordinateur. C&#039;est l&#039;ordinateur de Dieu. Ce n&#039;est pas votre maison. C&#039;est la maison de Dieu. Ce n&#039;est pas votre voiture. C&#039;est la voiture de Dieu. Ce n&#039;est pas votre enfant. C&#039;est l&#039;enfant de Dieu. Votre conjoint ne vous appartient pas. Il appartient \u00e0 Dieu. Ce n&#039;est pas votre corps. C&#039;est le corps de Dieu. Ce ne sont pas vos qualit\u00e9s et vos capacit\u00e9s. Ce sont les qualit\u00e9s et les capacit\u00e9s de Dieu. Tout appartient \u00e0 Dieu. Et vous \u00eates l&#039;intendant de tout ce dont Il vous confie la gestion, aussi longtemps qu&#039;Il vous la confie.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Puisque tout appartient \u00e0 Dieu, vous lui appartenez aussi. Vous \u00eates responsable devant Dieu, et Dieu seul, car vous appartenez \u00e0 Dieu seul. Vous n&#039;\u00eates pas responsable envers les autres, y compris votre conjoint. Vous \u00eates responsable devant Dieu. Mais votre responsabilit\u00e9 envers Dieu ne vous laisse pas indiff\u00e9rent. Vous \u00eates responsable devant Dieu de la fa\u00e7on dont vous traitez les autres, car ils lui appartiennent aussi. Et une v\u00e9ritable responsabilit\u00e9 envers Dieu signifie que vous aimez les autres, les traitez comme le Christ le ferait et pensez du bien d&#039;eux, m\u00eame lorsqu&#039;ils n&#039;en sont pas conscients, car vous savez que Dieu est toujours attentif. Vous n&#039;\u00eates pas seulement gentil quand ils vous regardent ou vous \u00e9coutent. Vous \u00eates gentil en permanence parce que Dieu vous regarde et vous \u00e9coute toujours.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;De quoi \u00eates-vous responsable devant Dieu\u00a0? \u00cates-vous responsable devant Dieu de ce que les autres pensent\u00a0? De ce qu\u2019ils disent\u00a0? De ce qu\u2019ils font\u00a0? De leurs r\u00e9actions\u00a0? Ou de leurs choix\u00a0? Bien s\u00fbr que non\u00a0! Vous n\u2019\u00eates responsable devant Dieu que de ce que vous pensez, dites, faites et de vos r\u00e9actions. Pourquoi\u00a0? Parce que vous n\u2019\u00eates responsable que de vos propres choix et d\u00e9cisions, et non de ceux des autres.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dieu a cr\u00e9\u00e9 chaque personne avec son propre esprit, sa propre volont\u00e9, son propre gouvernement. Et personne n&#039;est responsable du gouvernement d&#039;autrui. M\u00eame Dieu n&#039;assume aucune responsabilit\u00e9 pour le gouvernement d&#039;autrui. Oui, nous sommes responsables de notre gouvernement devant Lui, car nous Lui appartenons. Mais Il n&#039;est pas responsable de la fa\u00e7on dont nous nous gouvernons. Nous seuls le sommes.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;Lorsque nous prenons en charge une relation, nous nous rendons \u00e9galement responsables de l&#039;autre personne. Cela signifie que nous assumons la responsabilit\u00e9 de ses pens\u00e9es, de ses croyances, de ses choix, de ses d\u00e9cisions, de ses paroles et de ses actes \u2013 de son autonomie. Nous entrons alors dans un territoire o\u00f9 m\u00eame Dieu n&#039;oserait pas s&#039;aventurer. Je rends d\u00e9sormais l&#039;autre personne responsable envers moi, car je me suis rendu responsable d&#039;elle. Ses paroles, ses actes et ses r\u00e9actions, je les prends personnellement, car je consid\u00e8re tout cela comme ma propre responsabilit\u00e9. Et s&#039;il ne parle pas, n&#039;agit pas ou ne r\u00e9agit pas bien, je le prends comme une offense personnelle, car il est responsable envers moi. Et puisque l&#039;issue de la relation est de ma responsabilit\u00e9, car je la poss\u00e8de, je dois essayer de la r\u00e9parer ou de la corriger d&#039;une mani\u00e8re ou d&#039;une autre pour que la relation reste une r\u00e9ussite \u2013 afin que je puisse continuer \u00e0 r\u00e9ussir.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les r\u00e9sultats de la prise en charge d\u2019une relation sont nombreux :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Peur de l&#039;\u00e9chec<\/li>\n\n\n\n<li>En fonction de l&#039;autre personne<\/li>\n\n\n\n<li>Prendre leurs paroles et leurs actes personnellement<\/li>\n\n\n\n<li>Frustration<\/li>\n\n\n\n<li>D\u00e9ception<\/li>\n\n\n\n<li>Se sentir hors de contr\u00f4le<\/li>\n\n\n\n<li>Manipulation\u00a0<\/li>\n\n\n\n<li>Conflit<\/li>\n\n\n\n<li>S\u00e9paration<\/li>\n\n\n\n<li>L&#039;\u00e9chec de la relation<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Quelle est la solution \u00e0 ce probl\u00e8me ? C&#039;est d&#039;\u00eatre convaincu de la v\u00e9rit\u00e9. Et quelle est la v\u00e9rit\u00e9 ? La v\u00e9rit\u00e9, c&#039;est que vous n&#039;\u00eates jamais ma\u00eetre d&#039;une relation. Vous n&#039;\u00eates que le gardien de chaque relation. Vous n&#039;\u00eates jamais responsable de ce que l&#039;autre pense, dit, fait, ni de la fa\u00e7on dont il g\u00e8re sa relation. Vous n&#039;\u00eates responsable que de ce que vous pensez, dites, faites, et de la fa\u00e7on dont vous g\u00e9rez votre relation. Et vous n&#039;\u00eates jamais responsable de l&#039;issue de la relation, car celle-ci d\u00e9pend non seulement de vous, mais aussi de l&#039;autre. Et vous ne pouvez jamais contr\u00f4ler ni garantir sa part de la relation.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En tant qu&#039;intendant de chaque relation, vous n&#039;assumez la responsabilit\u00e9 que de votre c\u00f4t\u00e9. Vous assumez la responsabilit\u00e9 de vos pens\u00e9es, de vos paroles, de vos actes, de vos r\u00e9actions et de votre participation \u00e0 la relation. Vous reconnaissez que vous \u00eates responsable devant Dieu seul de votre autonomie dans la relation, et vous vous gouvernez en harmonie avec la volont\u00e9 de Dieu, ind\u00e9pendamment de ce que l&#039;autre personne en pense \u2013 car votre responsabilit\u00e9 est envers Dieu, et non envers l&#039;autre personne.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Encore une fois, cela ne vous rend pas insensible ou indiff\u00e9rent envers les autres. Bien au contraire. Lorsque vous avez Dieu comme source et que vous savez que vous g\u00e9rez la relation pour lui, vous profitez de son grand amour compatissant afin de pouvoir transmettre ce m\u00eame amour compatissant \u00e0 l&#039;autre personne dans la relation. Vous l&#039;aimez. Vous vous souciez de son bien-\u00eatre. Vous vivez pour servir ses int\u00e9r\u00eats. Mais vous n&#039;\u00eates pas contr\u00f4l\u00e9 par ses pens\u00e9es ou ses opinions. Vous \u00eates uniquement contr\u00f4l\u00e9 par les pens\u00e9es de Dieu.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Vous trouvez du r\u00e9confort dans le fait d&#039;\u00eatre l&#039;intendant de Dieu, recevant de Dieu les ressources n\u00e9cessaires pour les transmettre \u00e0 l&#039;autre personne dans la relation. Vous prenez votre r\u00f4le au s\u00e9rieux, peu importe ce que fait l&#039;autre personne dans la relation. S&#039;il se comporte mal, c&#039;est son probl\u00e8me personnel. Vous le plaignez d&#039;agir ainsi. Vous priez pour lui. Vous aspirez \u00e0 sa libert\u00e9. Mais vous continuez \u00e0 rester un intendant fid\u00e8le de Dieu envers cette personne, quel que soit son comportement. Vous n&#039;avez pas besoin qu&#039;elle aille bien pour que vous alliez bien. Vous avez seulement besoin que Dieu aille bien pour que vous alliez bien.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">On mesure le succ\u00e8s non pas \u00e0 l&#039;issue de la relation, mais \u00e0 la fa\u00e7on dont on g\u00e8re les ressources divines pour l&#039;autre. Le succ\u00e8s, c&#039;est avoir Dieu comme source et puiser en Lui tout ce dont on a besoin pour le donner librement \u00e0 l&#039;autre. S&#039;il se comporte bien, on prend \u00e0 Dieu pour donner. S&#039;il ne se comporte pas bien, on prend \u00e0 Dieu pour donner. S&#039;il est heureux, on prend \u00e0 Dieu pour donner. S&#039;il est triste, on prend \u00e0 Dieu pour donner. Vous pouvez r\u00e9ussir quels que soient son comportement, ses paroles, ses r\u00e9actions ou ses croyances, car votre r\u00e9ussite ne d\u00e9pend pas d&#039;eux. Elle ne d\u00e9pend que de Dieu et de vous.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Alors, s&#039;ils d\u00e9cident de vous quitter ou d&#039;abandonner la relation, ne le prenez pas personnellement. Vous ne le voyez pas comme une perte personnelle. Vous ne le voyez pas comme un \u00e9chec personnel. Vous les aimez. Vous souffrez pour eux. Vous les plaignez. Vous savez qu&#039;ils ne sont pas libres, car ils n&#039;acceptent pas l&#039;amour que Dieu leur offre \u00e0 travers vous. Vous d\u00e9sirez leur libert\u00e9 et vous \u00eates pr\u00eat \u00e0 faire tout ce que Dieu voudrait que vous fassiez pour les aider \u00e0 s&#039;\u00e9manciper. Mais vous n&#039;avez pas besoin d&#039;eux et vous pouvez les laisser partir s&#039;ils le souhaitent. Vous n&#039;avez besoin que de Dieu, et vous ne pouvez pas le laisser partir. L&#039;amour les laisse libres de s&#039;autogouverner, m\u00eame lorsqu&#039;ils le font de mani\u00e8re mauvaise et destructrice. C&#039;est cela la libert\u00e9. Et elle n&#039;est possible que si l&#039;on est un intendant, et non un propri\u00e9taire.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De toute \u00e9vidence, on ne passe pas imm\u00e9diatement du statut de propri\u00e9taire \u00e0 celui d&#039;intendant. On ne passe pas imm\u00e9diatement d&#039;une attitude toujours personnelle et d&#039;une volont\u00e9 de contr\u00f4ler l&#039;issue de ses relations \u00e0 une attitude sans jamais prendre les choses personnellement et \u00e0 laisser l&#039;autre personne libre de se gouverner. Il y a une p\u00e9riode de transition (souvent tr\u00e8s longue). \u00c0 quoi ressemble cette p\u00e9riode de transition\u00a0? Au d\u00e9but, on se sent comme propri\u00e9taire. \u00c0 la fin, on se sent comme un intendant. Et c&#039;est un va-et-vient entre les deux. C&#039;est comme un b\u00e9b\u00e9 qui apprend \u00e0 marcher. Se relever et retomber font partie du processus d&#039;apprentissage. Et la r\u00e9ussite se mesure \u00e0 la capacit\u00e9 \u00e0 se relever apr\u00e8s chaque chute. Au d\u00e9but, on tombe beaucoup. On passe beaucoup de temps au sol. On fait beaucoup d&#039;efforts pour se relever. Mais avec le temps, on se rel\u00e8ve plus vite, on reste debout plus longtemps et on tr\u00e9buche de moins en moins.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Au d\u00e9but, on apprend intellectuellement que les relations ne nous appartiennent pas et qu&#039;on n&#039;est pas responsable de la fa\u00e7on dont l&#039;autre y participe. Mais lorsqu&#039;il ne se comporte pas selon nos crit\u00e8res, on le prend personnellement, on s&#039;\u00e9nerve, on essaie de contr\u00f4ler les cons\u00e9quences, etc. (on chute). Que fait-on alors\u00a0? On se rel\u00e8ve. On se souvient de la v\u00e9rit\u00e9. On demande \u00e0 Dieu de l&#039;aider \u00e0 la faire p\u00e9n\u00e9trer dans son c\u0153ur afin que la conviction s&#039;installe. On apporte ses mauvaises r\u00e9actions \u00e0 la croix et on demande \u00e0 Dieu de remplacer sa nature d\u00e9chue par sa nature non d\u00e9chue. On accepte la vie du Christ en \u00e9change de sa vie. Et, fort de la confiance et de la puissance de la nature du Christ, on renoue avec la v\u00e9rit\u00e9, dans l&#039;amour et la puissance de Dieu. Chaque fois que l&#039;on chute, ne s&#039;en veut pas. Reviens simplement \u00e0 la croix et rel\u00e8ve-toi. Avec le temps, la r\u00e9p\u00e9tition et l&#039;abandon, le Saint-Esprit apportera cette v\u00e9rit\u00e9 dans votre c\u0153ur, vous permettant ainsi de r\u00e9agir de plus en plus automatiquement en harmonie avec elle, jusqu&#039;\u00e0 ce que vous r\u00e9alisiez que vous vivez la v\u00e9rit\u00e9 dans vos relations sans m\u00eame y penser ni vous y concentrer. Cela devient tout simplement une partie naturelle de votre vie. C&#039;est le processus. Cela prend du temps. Acceptez la gr\u00e2ce, la patience et la bont\u00e9 de Dieu envers vous pendant ce processus. Et sachez que votre P\u00e8re c\u00e9leste vous sourit tandis que vous apprenez \u00e0 marcher.&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Whether we have ever thought of it consciously or not, each of us takes ownership of the relationships in our lives. This may seem like a good thing, but is it? When we take ownership of a relationship, we take responsibility for its outcome. If it fails, we perceive that we failed. If it succeeds, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":9003,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[66],"tags":[148,145,143,142,146,141,147,144],"class_list":["post-9001","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-relationships","tag-accountability","tag-conflict","tag-ownership","tag-owning","tag-peace","tag-relationships","tag-responsibility","tag-stewardship"],"acf":[],"_links":{"self":[{"href":"https:\/\/npmin.org\/fr\/wp-json\/wp\/v2\/posts\/9001","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/npmin.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/npmin.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/npmin.org\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/npmin.org\/fr\/wp-json\/wp\/v2\/comments?post=9001"}],"version-history":[{"count":1,"href":"https:\/\/npmin.org\/fr\/wp-json\/wp\/v2\/posts\/9001\/revisions"}],"predecessor-version":[{"id":9004,"href":"https:\/\/npmin.org\/fr\/wp-json\/wp\/v2\/posts\/9001\/revisions\/9004"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/npmin.org\/fr\/wp-json\/wp\/v2\/media\/9003"}],"wp:attachment":[{"href":"https:\/\/npmin.org\/fr\/wp-json\/wp\/v2\/media?parent=9001"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/npmin.org\/fr\/wp-json\/wp\/v2\/categories?post=9001"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/npmin.org\/fr\/wp-json\/wp\/v2\/tags?post=9001"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}